{"id":15671,"date":"2018-12-10T21:05:37","date_gmt":"2018-12-10T20:05:37","guid":{"rendered":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/?p=15671"},"modified":"2018-12-10T21:26:55","modified_gmt":"2018-12-10T20:26:55","slug":"7-enfants-et-jeunes-de-notre-ensemble-paroissial-font-leur-entree-en-catechumenat","status":"publish","type":"post","link":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/7-enfants-et-jeunes-de-notre-ensemble-paroissial-font-leur-entree-en-catechumenat\/","title":{"rendered":"7 enfants et jeunes de notre ensemble paroissial font leur entr\u00e9e en cat\u00e9chum\u00e9nat."},"content":{"rendered":"<blockquote><p>Samedi 8 d\u00e9cembre, 7 enfants et jeunes faisaient leur 1re \u00e9tape de bapt\u00eame \u00e0 l\u2019\u00e9glise de Montberon.<\/p><\/blockquote>\n<p style=\"text-align: justify;\">En ce samedi de la f\u00eate de l\u2019Immacul\u00e9e Conception, 2 coll\u00e9giennes et 5 enfants du primaire ont officiellement demand\u00e9 le bapt\u00eame, entour\u00e9s de leurs familles et de la communaut\u00e9 paroissiale \u00e0 l\u2019\u00e9glise de Montberon. Une fa\u00e7on inattendue de commencer la marche de l\u2019Avent pr\u00e9c\u00e9d\u00e9e par notre Sainte M\u00e8re. Nous avons pri\u00e9 pour que, Notre M\u00e8re, l\u2019Immacul\u00e9e Conception qui a dit une grand oui de la foi, accompagne ces cat\u00e9chum\u00e8nes dans leur marche vers le bapt\u00eame. \u00a0Ces enfants et jeunes nous ont confi\u00e9 leur joie de faire partie de la famille des chr\u00e9tiens :<\/p>\n<ul>\n<li>\u00ab <em>Ma foi est arriv\u00e9e tout doucement<\/em> \u00bb (Kim Lan)<\/li>\n<li>\u00ab <em>Me faire baptiser me tient \u00e0 c\u0153ur<\/em> \u00bb\u00a0 (Nina)<\/li>\n<li>\u00ab <em>J\u2019ai envie d\u2019\u00eatre baptis\u00e9 comme papa et maman<\/em> \u00bb (Killian)<\/li>\n<li>\u00ab<em> Pour partager ma foi avec mon parrain et ma marraine<\/em> \u00bb (Alexiane)<\/li>\n<\/ul>\n<p>Notre communaut\u00e9 est heureuse d\u2019accueillir et d\u2019accompagner \u00a0ces enfants de Dieu. Ils r\u00e9veillent notre foi et nous donnent \u00e0 r\u00e9fl\u00e9chir sur le sens de notre engagement.<\/p>\n<p>Souhaitons leur bonne route jusqu\u2019au bapt\u00eame et portons-les dans notre pri\u00e8re.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Samedi 8 d\u00e9cembre, 7 enfants et jeunes faisaient leur 1re [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[103,83,94],"tags":[],"jetpack_featured_media_url":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-content\/uploads\/ETAPE-1-1.jpg","_links":{"self":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts\/15671"}],"collection":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/comments?post=15671"}],"version-history":[{"count":5,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts\/15671\/revisions"}],"predecessor-version":[{"id":15685,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts\/15671\/revisions\/15685"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/media\/15679"}],"wp:attachment":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/media?parent=15671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/categories?post=15671"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/tags?post=15671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}