{"id":16107,"date":"2019-04-08T23:16:26","date_gmt":"2019-04-08T22:16:26","guid":{"rendered":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/?p=16107"},"modified":"2019-04-08T23:16:26","modified_gmt":"2019-04-08T22:16:26","slug":"conference-de-pere-cyprien-comte-isaie-habacuc-jeremie-trois-prophetes-qui-vivifient-notre-foi-2","status":"publish","type":"post","link":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/conference-de-pere-cyprien-comte-isaie-habacuc-jeremie-trois-prophetes-qui-vivifient-notre-foi-2\/","title":{"rendered":"4\u00e8 conf\u00e9rence de car\u00eame : d\u00e9couvrez la pri\u00e8re d&rsquo;offrande avec le r\u00e9seau Mondial de Pri\u00e8re du Pape"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\"  style='background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;'><div class=\"fusion-builder-row fusion-row \"><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_1  fusion-one-full fusion-column-first fusion-column-last 1_1\"  style='margin-top:0px;margin-bottom:0px;'>\n\t\t\t\t\t<div class=\"fusion-column-wrapper\" style=\"padding: 0px 0px 0px 0px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"  data-bg-url=\"\">\n\t\t\t\t\t\t<div class=\"fusion-text\"><blockquote>\n<p><span style=\"font-weight: 400;\">Pr\u00e8s de 35 millions de personnes ! Le r\u00e9seau mondial de pri\u00e8re du pape rassemble des fid\u00e8les originaires d&rsquo;une centaine de pays dans le monde qui r\u00e9pondent au d\u00e9sir de Dieu de rassembler l&rsquo;humanit\u00e9. Ainsi, chaque mois, le pape discerne et publie une intention de pri\u00e8re -d\u00e9fi pour l&rsquo;humanit\u00e9- qui sert de fil conducteur \u00e0 une pri\u00e8re d&rsquo;offrande, pri\u00e8re eucharistique et pri\u00e8re missionnaire que chacun peut dire \u00e0 tout moment de la journ\u00e9e en union avec le monde entier ! D\u00e9couvrez le r\u00e9seau Mondial de pri\u00e8re que le p\u00e8re Daniel R\u00e9gent, p\u00e8re j\u00e9suite, directeur du R\u00e9seau mondial de la pri\u00e8re et Marie Dominique Corthier, la\u00efque, responsable europ\u00e9enne du r\u00e9seau, nous ont pr\u00e9sent\u00e9 lors de la derni\u00e8re conf\u00e9rence de Car\u00eame, le 28 mars dernier \u00e0 Pechbonnieu. Un enseignement qui a particuli\u00e8rement touch\u00e9 Guy de Beler qui nous en livre ici l&rsquo;essentiel.<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Plus qu&rsquo;une pr\u00e9sentation, le p\u00e8re Daniel R\u00e9gent (religieux j\u00e9suite) et Marie Dominique Corthier (la\u00efque) nous ont surtout fait vivre ce qu\u2019est le r\u00e9seau Mondial de Pri\u00e8re du Pape au cours d\u2019une soir\u00e9e tr\u00e8s vivante. Je retiens personnellement 4 mots phares qui ont \u00e9t\u00e9 mis en valeur par nos deux intervenants :<\/span><\/p>\n<p><b>Offrir : J\u00e9sus s\u2019offre \u00e0 moi, en retour j\u2019offre ma journ\u00e9e. <\/b><span style=\"font-weight: 400;\">Offrir les activit\u00e9s de la journ\u00e9e, par amour en s\u2019unissant au c\u0153ur de J\u00e9sus. A la messe dominicale pendant l\u2019offertoire, j\u2019offre \u00e0 J\u00e9sus travail, joies et peines de la semaine avant que J\u00e9sus ne s\u2019offre \u00e0 nous dans l\u2019Eucharistie.<\/span><\/p>\n<p><b>Amour :<\/b><span style=\"font-weight: 400;\"> En nous associant \u00e0 cette pri\u00e8re du pape, nous rejoignons une des intuitions profondes de Sainte Th\u00e9r\u00e8se de l\u2019Enfant J\u00e9sus : ce n\u2019est pas de faire beaucoup qui compte aux yeux du Seigneur mais de <\/span><b>mettre de l\u2019amour dans ce que l\u2019on fait.<\/b><\/p>\n<p><b>Mission<\/b><span style=\"font-weight: 400;\"> : En rejoignant le r\u00e9seau mondial de la pri\u00e8re du Pape -35 millions de personnes dans le monde-, <\/span><b>nous nous rendons disponibles <\/b><span style=\"font-weight: 400;\">pour la mission, et nous sommes invit\u00e9s \u00e0 porter la mission du Christ avec lui. Le travail de la mission commence par nous. Et le fait d\u2019aller en mission me remet debout.<\/span><\/p>\n<p><b>C\u0153ur <\/b><span style=\"font-weight: 400;\">: Tr\u00e8s belle m\u00e9ditation du p\u00e8re R\u00e9gent sur <\/span><b>la pri\u00e8re d\u2019offrande qui est r\u00e9cit\u00e9e avant la pri\u00e8re du mois. Nous demandons au P\u00e8re d\u2019unir mon c\u0153ur au c\u0153ur de son fils J\u00e9sus.<\/b><span style=\"font-weight: 400;\"> Dieu a un c\u0153ur compatissant pour sa cr\u00e9ation. Au XVII\u00e8me si\u00e8cle une religieuse visitandine : Marguerite- Marie nous fait conna\u00eetre le c\u0153ur de J\u00e9sus. Pour r\u00e9concilier le c\u0153ur et la t\u00eate raisonnante (cogito de Descartes), laisse-moi affirmer que la vie vient de Dieu.<\/span><\/p>\n<h2><b>Petit fioretti<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Ce mois-ci le pape nous demande de prier pour les m\u00e9decins et humanitaires pr\u00e9sents dans les zones de combat qui risquent leur vie pour sauver celle des autres. Et justement ce matin, nous apprenons par une relation sur Facebook la mort d\u2019un jeune m\u00e9decin militaire de 30 ans au Mali dont la voiture a explos\u00e9. En voyant sa photo, \u00e9mu j\u2019ai pri\u00e9 pour lui, pour sa femme, sa famille et les soldats pr\u00e9sents l\u00e0-bas.<\/span><\/p>\n<\/div><div class=\"fusion-testimonials classic fusion-testimonials-1\" data-random=\"0\" data-speed=\"4000\"><style type=\"text\/css\" scoped=\"scoped\">#fusion-testimonials-1 a{border-color:#747474;}#fusion-testimonials-1 a:hover, #fusion-testimonials-1 .activeSlide{background-color: #747474;}.fusion-testimonials.classic.fusion-testimonials-1 .author:after{border-top-color:#f6f6f6 !important;}<\/style><div class=\"reviews\"><div class=\"review male\"><blockquote><q style=\"background-color:#f6f6f6;color:#747474;\" class=\"fusion-clearfix\">\n<h2><strong>Comment rejoindre le R\u00e9seau mondial de pri\u00e8re du Pape :<\/strong><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">sur le site internet :<\/span><a href=\"https:\/\/www.prieraucoeurdumonde.net\/video-du-pape\/\"> <span style=\"font-weight: 400;\">https:\/\/www.prieraucoeurdumonde.net\/video-du-pape\/<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">sur l&rsquo;application smartphone : ClickToPlay<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">en vous abonnant au trimestriel de l&rsquo;Apostolat de la pri\u00e8re : \u00ab Avec le Christ \u00bb, SER, 14 rue d&rsquo;Assas, 75 006, Paris. Contact : 01 44 39 48 04. (5,60 \u20ac\/an)<\/span><\/p>\n<\/q><\/blockquote><\/div><\/div><\/div><div class=\"fusion-testimonials classic fusion-testimonials-2\" data-random=\"0\" data-speed=\"4000\"><style type=\"text\/css\" scoped=\"scoped\">#fusion-testimonials-2 a{border-color:#747474;}#fusion-testimonials-2 a:hover, #fusion-testimonials-2 .activeSlide{background-color: #747474;}.fusion-testimonials.classic.fusion-testimonials-2 .author:after{border-top-color:#f6f6f6 !important;}<\/style><div class=\"reviews\"><div class=\"review male\"><blockquote><q style=\"background-color:#f6f6f6;color:#747474;\" class=\"fusion-clearfix\">\n<h2 style=\"text-align: justify;\"><strong>Prier avec le d\u00e9fi du mois d&rsquo;avril 2019 :<\/strong><\/h2>\n<p style=\"text-align: justify;\"><b>Prions pour les m\u00e9decins et les humanitaires pr\u00e9sents dans les zones de combat qui risquent leur vie pour sauver celle des autres.<\/b><\/p>\n<p style=\"text-align: justify;\"><b>Pri\u00e8re :<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00ab P\u00e8re tr\u00e8s bon, Toi qui contemple ton Fils J\u00e9sus nous nous sentons appel\u00e9s \u00e0 la g\u00e9n\u00e9rosit\u00e9, \u00e0 donner la priorit\u00e9 aux besoins de nos fr\u00e8res et s\u0153urs, sur notre confort et notre s\u00e9curit\u00e9. Aide-nous \u00e0 ne pas rester indiff\u00e9rents ou paresseux pour que nous accomplissions bien ce qui est \u00e0 notre port\u00e9e. Nous te demandons que ta gr\u00e2ce soit la force des m\u00e9decins et du personnel b\u00e9n\u00e9vole qui sont au service des victimes de la guerre. Sois leur protection dans les moments de d\u00e9couragement et de fatigue, afin que leur exemple soit lumi\u00e8re au milieu des t\u00e9n\u00e8bres.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Notre p\u00e8re&#8230;<\/span><\/p>\n<p style=\"text-align: justify;\"><b>Pri\u00e8re d&rsquo;offrande :<\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">P\u00e8re tr\u00e8s bon, je sais que Tu es toujours avec moi, me voici en ce jour nouveau.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Mets mon c\u0153ur, une fois encore aupr\u00e8s du C\u0153ur de Ton Fils J\u00e9sus, qui s&rsquo;offre pour moi et qui vient \u00e0 moi dans l&rsquo;Eucharistie.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Que ton Esprit Saint fasse de moi son ami et ap\u00f4tre, disponible \u00e0 sa mission.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Je mets en tes mains mes joies et mes esp\u00e9rances, mes activit\u00e9s et mes souffrances, tout ce que j&rsquo;ai et poss\u00e8de, en communion avec mes fr\u00e8res e s\u0153urs de ce r\u00e9seau mondial de pri\u00e8re.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Avec Marie, je t&rsquo;offre cette journ\u00e9e pour la mission de l\u2019\u00c9glise et pour les intentions de pri\u00e8res du pas de ce mois : <\/span><b>pour les m\u00e9decins et les humanitaires pr\u00e9sents dans les zones de combat qui risquent leur vie pour sauver celle des autres.<\/b><\/p>\n<\/q><\/blockquote><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":16118,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[93,94,69],"tags":[],"jetpack_featured_media_url":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-content\/uploads\/ReseauMondialPape-2-e1554761515735.jpg","_links":{"self":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts\/16107"}],"collection":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/comments?post=16107"}],"version-history":[{"count":10,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts\/16107\/revisions"}],"predecessor-version":[{"id":16121,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts\/16107\/revisions\/16121"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/media\/16118"}],"wp:attachment":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/media?parent=16107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/categories?post=16107"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/tags?post=16107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}