{"id":16638,"date":"2019-08-30T23:42:52","date_gmt":"2019-08-30T22:42:52","guid":{"rendered":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/?p=16638"},"modified":"2019-08-30T23:42:52","modified_gmt":"2019-08-30T22:42:52","slug":"inscriptions-kt","status":"publish","type":"post","link":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/inscriptions-kt\/","title":{"rendered":"Inscriptions KT"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">De la petite section de maternelle \u00e0 la 3\u00e8me, les inscriptions \u00e0 l\u2019\u00e9veil \u00e0 la foi, au cat\u00e9chisme et \u00e0 l\u2019aum\u00f4nerie se feront le mercredi 18 septembre de 15h \u00e0 18h au centre pastoral de Castelginest et le samedi 21 septembre de 9h30 \u00e0 12h au centre pastoral de Labastide St Sernin.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Vous pourrez inscrire tous vos enfants et jeunes le m\u00eame jour. Que ce soit \u00e0 Castelginest ou \u00e0 Labastide, tous les groupes seront repr\u00e9sent\u00e9s, les inscriptions seront ainsi possibles pour Lalande, Aucamville, Castelginest, Saint Alban, Saint Loup Cammas ou Labastide.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Dites-le autour de vous, invitez les copains\/copines, voisins\/voisines \u00e0 partager cette belle d\u00e9couverte de notre Seigneur J\u00e9sus dans des groupes dynamiques et ouverts.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De la petite section de maternelle \u00e0 la 3\u00e8me, les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16640,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[84,81,76,94],"tags":[],"jetpack_featured_media_url":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-content\/uploads\/AFIICHE-KT-2-pdf.jpg","_links":{"self":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts\/16638"}],"collection":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/comments?post=16638"}],"version-history":[{"count":1,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts\/16638\/revisions"}],"predecessor-version":[{"id":16639,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/posts\/16638\/revisions\/16639"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/media\/16640"}],"wp:attachment":[{"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/media?parent=16638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/categories?post=16638"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.paroisse-aucamville-st-loup-cammas.fr\/site\/wp-json\/wp\/v2\/tags?post=16638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}